{"id":155,"date":"2017-06-15T07:30:14","date_gmt":"2017-06-15T07:30:14","guid":{"rendered":"http:\/\/dummy.xtemos.com\/woodmart\/?post_type=portfolio&amp;p=155"},"modified":"2017-06-15T07:30:14","modified_gmt":"2017-06-15T07:30:14","slug":"venenatis-nam-phasellus","status":"publish","type":"portfolio","link":"https:\/\/ektorashome.gr\/el\/portfolio\/venenatis-nam-phasellus\/","title":{"rendered":"Venenatis nam phasellus"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1481476949915 vc_row-o-equal-height vc_row-o-content-top vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"wood portfolio placeholder\" title=\"wood portfolio placeholder\" srcset=\"https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder.jpg 1200w, https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder-600x600.jpg 600w, https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder-150x150.jpg 150w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"wood portfolio placeholder\" title=\"wood portfolio placeholder\" srcset=\"https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder.jpg 1200w, https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder-600x600.jpg 600w, https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder-150x150.jpg 150w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"wood portfolio placeholder\" title=\"wood portfolio placeholder\" srcset=\"https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder.jpg 1200w, https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder-600x600.jpg 600w, https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder-150x150.jpg 150w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"wood portfolio placeholder\" title=\"wood portfolio placeholder\" srcset=\"https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder.jpg 1200w, https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder-600x600.jpg 600w, https:\/\/ektorashome.gr\/wp-content\/uploads\/2017\/06\/wood-portfolio-placeholder-150x150.jpg 150w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-4 woodmart-sticky-column wd_sticky_offset_150\"><div class=\"vc_column-inner vc_custom_1494491003828\"><div class=\"wpb_wrapper\"><h4 style=\"font-size: 46px;text-align: left\" class=\"vc_custom_heading vc_custom_1494490919124\" >Sticky Sidebar<\/h4><h5 style=\"color: #989898;text-align: left\" class=\"vc_custom_heading vc_custom_1481474849849\" >Details available with Every Demo<\/h5>\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1481474845707\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Hac vitae sem class fames\u00a0vehicula nascetur nam tellus a condimentum inceptos mus rhoncus et accumsan fringilla vehicula nascetur amet fermentum rutrum.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table>\n<tbody>\n<tr>\n<th>Client<\/th>\n<td style=\"text-align: right\">WordPress<\/td>\n<\/tr>\n<tr>\n<th>Designer<\/th>\n<td style=\"text-align: right\">John Doe<\/td>\n<\/tr>\n<tr>\n<th>Materials<\/th>\n<td style=\"text-align: right\">Wood, Paper<\/td>\n<\/tr>\n<tr>\n<th>Website<\/th>\n<td style=\"text-align: right\">xtemos.com\/wood<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_row-o-equal-height vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-5\"><div class=\"vc_column-inner vc_custom_1481476631480\"><div class=\"wpb_wrapper\"><div id=\"wd-6a050679a3572\" class=\"  wd-button-wrapper text-left\"><a  class=\"btn btn-color-black btn-style-default btn-style-rectangle btn-size-default btn-full-width\">View Project<\/a><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-7\"><div class=\"vc_column-inner vc_custom_1481476640791\"><div class=\"wpb_wrapper\">\n\t\t\t<div class=\" wd-social-icons  icons-design-colored icons-size-small color-scheme-dark social-share social-form-circle text-right\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Sticky SidebarDetails available with Every Demo Hac vitae sem class fames\u00a0vehicula nascetur nam tellus a condimentum inceptos mus rhoncus et","protected":false},"featured_media":117,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","project-cat":[33],"class_list":["post-155","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","project-cat-lighting"],"_links":{"self":[{"href":"https:\/\/ektorashome.gr\/el\/wp-json\/wp\/v2\/portfolio\/155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ektorashome.gr\/el\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/ektorashome.gr\/el\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/ektorashome.gr\/el\/wp-json\/wp\/v2\/comments?post=155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ektorashome.gr\/el\/wp-json\/wp\/v2\/media\/117"}],"wp:attachment":[{"href":"https:\/\/ektorashome.gr\/el\/wp-json\/wp\/v2\/media?parent=155"}],"wp:term":[{"taxonomy":"project-cat","embeddable":true,"href":"https:\/\/ektorashome.gr\/el\/wp-json\/wp\/v2\/project-cat?post=155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}